{"id":34862,"date":"2024-02-08T10:26:06","date_gmt":"2024-02-08T10:26:06","guid":{"rendered":"https:\/\/demo.itlas.com\/?post_type=cp_realizzazione&#038;p=34862"},"modified":"2024-04-09T13:41:59","modified_gmt":"2024-04-09T13:41:59","slug":"colle-loreto","status":"publish","type":"cp_realizzazione","link":"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto","title":{"rendered":"Colle Loreto"},"template":"","ct_essenza":[1144],"ct_finitura":[681],"ct_linea":[1046],"ct_tipologia_realizzazione":[1060],"class_list":["post-34862","cp_realizzazione","type-cp_realizzazione","status-publish","hentry","ct_essenza-teak-3","ct_finitura-y011-accadueo","ct_linea-legni-del-doge-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>R\u00e9alisation Colle Loreto d&#039;un \u00e9tage Legni del Doge | ITLAS<\/title>\n<meta name=\"description\" content=\"Le teck marin, finition Accadueo, a \u00e9t\u00e9 utilis\u00e9 pour le rev\u00eatement de sol de la piscine d&#039;un complexe r\u00e9sidentiel de luxe \u00e0 Lugano.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00e9alisation Colle Loreto d&#039;un \u00e9tage Legni del Doge | ITLAS\" \/>\n<meta property=\"og:description\" content=\"Le teck marin, finition Accadueo, a \u00e9t\u00e9 utilis\u00e9 pour le rev\u00eatement de sol de la piscine d&#039;un complexe r\u00e9sidentiel de luxe \u00e0 Lugano.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto\" \/>\n<meta property=\"og:site_name\" content=\"Itlas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-09T13:41:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto\",\"url\":\"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto\",\"name\":\"R\u00e9alisation Colle Loreto d'un \u00e9tage Legni del Doge | ITLAS\",\"isPartOf\":{\"@id\":\"https:\/\/www.itlas.com\/fr\/#website\"},\"datePublished\":\"2024-02-08T10:26:06+00:00\",\"dateModified\":\"2024-04-09T13:41:59+00:00\",\"description\":\"Le teck marin, finition Accadueo, a \u00e9t\u00e9 utilis\u00e9 pour le rev\u00eatement de sol de la piscine d'un complexe r\u00e9sidentiel de luxe \u00e0 Lugano.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.itlas.com\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Colle Loreto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.itlas.com\/fr\/#website\",\"url\":\"https:\/\/www.itlas.com\/fr\/\",\"name\":\"Itlas\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.itlas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00e9alisation Colle Loreto d'un \u00e9tage Legni del Doge | ITLAS","description":"Le teck marin, finition Accadueo, a \u00e9t\u00e9 utilis\u00e9 pour le rev\u00eatement de sol de la piscine d'un complexe r\u00e9sidentiel de luxe \u00e0 Lugano.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto","og_locale":"fr_FR","og_type":"article","og_title":"R\u00e9alisation Colle Loreto d'un \u00e9tage Legni del Doge | ITLAS","og_description":"Le teck marin, finition Accadueo, a \u00e9t\u00e9 utilis\u00e9 pour le rev\u00eatement de sol de la piscine d'un complexe r\u00e9sidentiel de luxe \u00e0 Lugano.","og_url":"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto","og_site_name":"Itlas","article_modified_time":"2024-04-09T13:41:59+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto","url":"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto","name":"R\u00e9alisation Colle Loreto d'un \u00e9tage Legni del Doge | ITLAS","isPartOf":{"@id":"https:\/\/www.itlas.com\/fr\/#website"},"datePublished":"2024-02-08T10:26:06+00:00","dateModified":"2024-04-09T13:41:59+00:00","description":"Le teck marin, finition Accadueo, a \u00e9t\u00e9 utilis\u00e9 pour le rev\u00eatement de sol de la piscine d'un complexe r\u00e9sidentiel de luxe \u00e0 Lugano.","breadcrumb":{"@id":"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.itlas.com\/fr\/realisations\/colle-loreto#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.itlas.com\/fr"},{"@type":"ListItem","position":2,"name":"Colle Loreto"}]},{"@type":"WebSite","@id":"https:\/\/www.itlas.com\/fr\/#website","url":"https:\/\/www.itlas.com\/fr\/","name":"Itlas","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itlas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/cp_realizzazione\/34862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/cp_realizzazione"}],"about":[{"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/types\/cp_realizzazione"}],"wp:attachment":[{"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/media?parent=34862"}],"wp:term":[{"taxonomy":"ct_essenza","embeddable":true,"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/ct_essenza?post=34862"},{"taxonomy":"ct_finitura","embeddable":true,"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/ct_finitura?post=34862"},{"taxonomy":"ct_linea","embeddable":true,"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/ct_linea?post=34862"},{"taxonomy":"ct_tipologia_realizzazione","embeddable":true,"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/ct_tipologia_realizzazione?post=34862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}