{"id":14474,"date":"2024-02-29T09:44:45","date_gmt":"2024-02-29T08:44:45","guid":{"rendered":"https:\/\/demo.itlas.com\/cp_pavimento\/tavole-del-piave-noce-daniela-a021-materia-2\/"},"modified":"2024-02-29T09:44:46","modified_gmt":"2024-02-29T09:44:46","slug":"tavole-del-piave-noce-daniela-a021-materia-2","status":"publish","type":"cp_pavimento","link":"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia","title":{"rendered":"Tavole del Piave &#8211; Noce daniela &#8211; A021 Materia"},"template":"","ct_classe_aspetto":[785,790],"ct_essenza":[655],"ct_finitura":[670],"ct_linea":[1047],"class_list":["post-14474","cp_pavimento","type-cp_pavimento","status-publish","hentry","ct_essenza-noyer-daniela","ct_finitura-a021-materia","ct_linea-tavole-del-piave-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tavole del Piave - Noce daniela - A021 Materia - Itlas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tavole del Piave - Noce daniela - A021 Materia - Itlas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia\" \/>\n<meta property=\"og:site_name\" content=\"Itlas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-29T09:44:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia\",\"url\":\"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia\",\"name\":\"Tavole del Piave - Noce daniela - A021 Materia - Itlas\",\"isPartOf\":{\"@id\":\"https:\/\/www.itlas.com\/fr\/#website\"},\"datePublished\":\"2024-02-29T08:44:45+00:00\",\"dateModified\":\"2024-02-29T09:44:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.itlas.com\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tavole del Piave &#8211; Noce daniela &#8211; A021 Materia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.itlas.com\/fr\/#website\",\"url\":\"https:\/\/www.itlas.com\/fr\/\",\"name\":\"Itlas\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.itlas.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tavole del Piave - Noce daniela - A021 Materia - Itlas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia","og_locale":"fr_FR","og_type":"article","og_title":"Tavole del Piave - Noce daniela - A021 Materia - Itlas","og_url":"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia","og_site_name":"Itlas","article_modified_time":"2024-02-29T09:44:46+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia","url":"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia","name":"Tavole del Piave - Noce daniela - A021 Materia - Itlas","isPartOf":{"@id":"https:\/\/www.itlas.com\/fr\/#website"},"datePublished":"2024-02-29T08:44:45+00:00","dateModified":"2024-02-29T09:44:46+00:00","breadcrumb":{"@id":"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.itlas.com\/fr\/tavole-del-piave\/noyer-daniela-a021-materia#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.itlas.com\/fr"},{"@type":"ListItem","position":2,"name":"Tavole del Piave &#8211; Noce daniela &#8211; A021 Materia"}]},{"@type":"WebSite","@id":"https:\/\/www.itlas.com\/fr\/#website","url":"https:\/\/www.itlas.com\/fr\/","name":"Itlas","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.itlas.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/cp_pavimento\/14474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/cp_pavimento"}],"about":[{"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/types\/cp_pavimento"}],"wp:attachment":[{"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/media?parent=14474"}],"wp:term":[{"taxonomy":"ct_classe_aspetto","embeddable":true,"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/ct_classe_aspetto?post=14474"},{"taxonomy":"ct_essenza","embeddable":true,"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/ct_essenza?post=14474"},{"taxonomy":"ct_finitura","embeddable":true,"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/ct_finitura?post=14474"},{"taxonomy":"ct_linea","embeddable":true,"href":"https:\/\/www.itlas.com\/fr\/wp-json\/wp\/v2\/ct_linea?post=14474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}